{"id":4517,"date":"2024-06-30T16:51:58","date_gmt":"2024-06-30T14:51:58","guid":{"rendered":"https:\/\/dev-eb2.abraxis-kassel.de\/?p=4517"},"modified":"2024-08-16T10:53:53","modified_gmt":"2024-08-16T08:53:53","slug":"russische-kriegsverbrechen-in-der-ukraine","status":"publish","type":"post","link":"https:\/\/kassel-ebb.eu\/de\/2024\/06\/russische-kriegsverbrechen-in-der-ukraine\/","title":{"rendered":"Russische Kriegsverbrechen in der Ukraine"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/lets-meet.org\/reg\/38b0acb88282ebbd13\" target=\"_blank\" rel=\"noopener\">Zur Anmeldung!<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zuerst werden einige Definitionen gekl\u00e4rt: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was ist ein Kriegsverbrechen? Welche Handlungen sind als solche zu bezeichnen? Wie sind sie im internationalen Recht definiert? Welche M\u00f6glichkeiten gibt es, um die Rechte der Betroffenen wiederherzustellen? Wir sprechen \u00fcber die Herausforderungen, mit denen die Ukraine in diesem Zusammenhang konfrontiert ist.\u00a0\u00a0Des Weiteren widmen wir uns dem \u00d6kozid, gehen auf einige Merkmale des V\u00f6lkermords ein und weisen auf sexuelle Gewalt russischer Truppen in der Ukraine hin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Workshopleiterin:<\/strong> Prof. Kateryna Ilikchiieva<br><strong>Treffpunkt:<\/strong> Neue Denkerei, Friedrichsstra\u00dfe 28, 34117 Kassel<br><strong>Sprache:<\/strong> Ukrainian, with German translation<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/lets-meet.org\/reg\/38b0acb88282ebbd13\" target=\"_blank\" rel=\"noopener\">Zur Anmeldung!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Anmeldung! Zuerst werden einige Definitionen gekl\u00e4rt: Was ist ein Kriegsverbrechen? Welche Handlungen sind als solche zu bezeichnen? Wie sind sie im internationalen Recht definiert? Welche M\u00f6glichkeiten gibt es, um die Rechte der Betroffenen wiederherzustellen? Wir sprechen \u00fcber die Herausforderungen, mit denen die Ukraine in diesem Zusammenhang konfrontiert ist.\u00a0\u00a0Des Weiteren widmen wir uns dem \u00d6kozid, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-4517","post","type-post","status-publish","format-standard","hentry","category-uncategorized-de"],"_links":{"self":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts\/4517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/comments?post=4517"}],"version-history":[{"count":0,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts\/4517\/revisions"}],"wp:attachment":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/media?parent=4517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/categories?post=4517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/tags?post=4517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}