{"id":3870,"date":"2023-03-16T16:24:07","date_gmt":"2023-03-16T14:24:07","guid":{"rendered":"https:\/\/dev-eb2.abraxis-kassel.de\/?p=3870"},"modified":"2023-03-28T15:55:29","modified_gmt":"2023-03-28T13:55:29","slug":"save-the-date-3-ebb-in-kassel","status":"publish","type":"post","link":"https:\/\/kassel-ebb.eu\/de\/2023\/03\/save-the-date-3-ebb-in-kassel\/","title":{"rendered":"Save the Date: 3. EBB in Kassel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>3. EBB in 2024 \u2013 Vom 12.09. bis zum 15.09.2024 in Kassel<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Termin f\u00fcr die 3. EBB steht bereits fest! Sie findet vom 12.09. bis 15.09.2024 in Kassel statt. Danach findet die B\u00fcrgerbegegnung im regelm\u00e4\u00dfigen Abstand alle zwei Jahre am zweiten vollen Septemberwochenende statt. Ihr k\u00f6nnt es euch also schon f\u00fcr die n\u00e4chsten Jahre freihalten. \ud83d\ude09<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir steigen schon voll in die Planung ein und freuen uns, euch wieder ein vielf\u00e4ltiges und spannendes Programm bieten zu k\u00f6nnen! Auch eure Anmerkungen und Anregungen lassen wir gerne in den Planungsprozess einflie\u00dfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Zwischenzeit wollen wir zu verschiedenen Themen (digitale) Workshops und Stammtische anbieten. In den Veranstaltungen k\u00f6nnen wir uns dann online schon vor der n\u00e4chsten EBB wiedersehen und miteinander ins Gespr\u00e4ch kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir freuen uns auch dar\u00fcber, wenn ihr in eurem Bekanntenkreis den neuen Termin f\u00fcr die EBB bekannt macht! Dann k\u00f6nnen wir im September gemeinsam neue Bekanntschaften mit Europ\u00e4erinnen und Europ\u00e4ern machen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3. EBB in 2024 \u2013 Vom 12.09. bis zum 15.09.2024 in Kassel Der Termin f\u00fcr die 3. EBB steht bereits fest! Sie findet vom 12.09. bis 15.09.2024 in Kassel statt. Danach findet die B\u00fcrgerbegegnung im regelm\u00e4\u00dfigen Abstand alle zwei Jahre am zweiten vollen Septemberwochenende statt. Ihr k\u00f6nnt es euch also schon f\u00fcr die n\u00e4chsten Jahre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-3870","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts\/3870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/comments?post=3870"}],"version-history":[{"count":0,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/posts\/3870\/revisions"}],"wp:attachment":[{"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/media?parent=3870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/categories?post=3870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kassel-ebb.eu\/de\/wp-json\/wp\/v2\/tags?post=3870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}